{"id":16604,"date":"2020-04-14T09:36:33","date_gmt":"2020-04-14T07:36:33","guid":{"rendered":"https:\/\/www.gamberetta.it\/it\/?p=16604"},"modified":"2022-10-29T14:50:25","modified_gmt":"2022-10-29T12:50:25","slug":"avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing","status":"publish","type":"post","link":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/","title":{"rendered":"AVVENTURE IN LAOS E CAMBOGIA: DALL&#8217;ITALIA A BANGKOK E MUANG SING"},"content":{"rendered":"\n<p>8 \u2013 10 AGOSTO 2014 (aereo e bus)<\/p>\n\n\n\n<p>Scrivo sul diario: <em>\u201cBella partenza con un gruppo bellissimo. Scrivo dal pulmino grande e senza A\/C nel tragitto da Huang Xai a Luang Namtha e Muang Sing, sono 200 km e l&#8217;autista dice che ci metteremo sei ore. Il nostro viaggio in L-C \u00e8 iniziato due giorni fa. Il giorno 8 agosto 2014, l&#8217;altro ieri, siamo partiti dall&#8217;Italia\u201d<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8 agosto 2014<\/h2>\n\n\n\n<p>Alle 15 prendiamo il treno da Mestre, un Freccia bianca che ho preso mille altre volte e ora per\u00f2 con lo zaino in mano ha proprio il dolce sapore del viaggio. Alla banchina incontro Ale 1 che sta in provincia di Treviso. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-1024x768.jpg\" alt=\"\" class=\"wp-image-16614\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ale 2 sta a Milano e lo troviamo a Malpensa, arrivato alla spicciolata come gli altri partecipanti \u201cmilanesi\u201d. I primi due arrivano in auto in stazione centrale, sono Giorgio e Franco, detto \u201cgelato\u201d.<\/p>\n\n\n\n<p>Attraversiamo il centro della citt\u00e0, deserta per l&#8217;esodo della settimana di ferragosto, e da Viale Certosa (vuoto) imbocchiamo l&#8217;autostrada in direzione aeroporto. Mi avvio al banco avventure per ritirare la busta del \u201cbravo coordinatore\u201d (non \u00e8 vero, la danno a tutti eh) e saluto Nadia, l&#8217;unica persona che conosco in mezzo a una lunga fila di viaggiatori in partenza per le mete pi\u00f9 disparate. Lei va in Sudafrica.<\/p>\n\n\n\n<p>Laura e Daniele vengono da Bergamo e \u2013 dicono poi \u2013 mi riconoscono dagli occhiali verdi della mia foto su Whatsapp, memori dei messaggi scambiati prima della partenza. Niente gruppo whatsapp, lo faremo a met\u00e0 viaggio senza peraltro sentirne la mancanza fino a quel momento, stiamo bene insieme, davvero e \u201cdal vero\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-1024x768.jpg\" alt=\"\" class=\"wp-image-16612\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110440.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Facciamo il nostro check-in e andiamo dietro i banchi a mangiare qualcosa in un baretto figo dove Ale 2 e Arianna ci raggiungono. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153716-768x1024.jpg\" alt=\"\" class=\"wp-image-16613\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153716-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153716-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153716-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153716.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Controllo bagagli e passaporti ok, saliamo sull&#8217;aereo che parte con mezz&#8217;ora di ritardo causa temporale. Sul volo MXP \u2013 DXB siamo otto, gli altri quattro pax ci raggiungono da Roma FCO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">9 agosto 2014<\/h2>\n\n\n\n<p>Colazione da Starbucks, wifi non funzionante e non vediamo i quattro pax \u201cromani\u201d fino al gate. Sono Terry e Gianfry da Vicenza, Orietta pure da Vicenza e infine Paola che viene da Perugia. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-1024x768.jpg\" alt=\"\" class=\"wp-image-16615\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153026.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Lei \u00e8 la pax numero uno con cui ho viaggiato dieci anni prima, nel 2004, nella mia prima avventura da coordinatrice in Siria, Libano e Giordania. Quest&#8217;ultima \u00e8 una destinazione molto gettonata da quasi vent&#8217;anni, luoghi che dovrebbero essere di pace mentre la Siria \u00e8 tormentata da una guerra senza fine e la penso con infinito dolore.<\/p>\n\n\n\n<p>Ci imbarcano sul volo DXB \u2013 BKK su un aereo enorme dove forse ci sono 600 posti, e nonostante le dimensioni balliamo un bel po&#8217;. Mangiamo, beviamo, dormiamo, atterriamo alle 19, ora locale. Ritiriamo i bagagli senza sorprese, idem al controllo passaporti, e ci dirigiamo al transfer (gratuito presentando il biglietto aereo) per l&#8217;aeroporto Don Muang da dove domattina partir\u00e0 il volo interno Air Asia per Chiang Rai.<\/p>\n\n\n\n<p>Ho prenotato il vicino hotel Amari con un eccellente rapporto qualit\u00e0 prezzo. Saliamo un attimo nelle stanze e in breve, lavati e cambiati, usciamo per cena ma con poca fame, sono le 22 e siamo in giro da 24 ore! Facciamo due passi, troviamo un ristorantino \u201cavventure style\u201d che fa al caso nostro, con un euro e mezzo a testa ci d\u00e0 un bel piatto di riso o noodles ma&#8230; non ha bevande e accetta solo contanti. Come fare?<\/p>\n\n\n\n<p>Andiamo a prendere acqua e birra al 7 eleven accanto, pago tutto io con i baht che avevo provvidenzialmente portato dal precedente viaggio a BKK, una benedizione per me e per il gruppo riconoscente (mi offriranno tanto durante il viaggio e glie ne sono grata). A mezzanotte come moderne Cenerentole rientriamo in hotel, cotti e pronti per dormire, non prima per\u00f2 di avere fatto una chiacchiera in camera con Paola. Buona notte!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">10 agosto 2014<\/h2>\n\n\n\n<p>Alle cinque siamo svegli, dopo mezz&#8217;ora usciamo dall&#8217;hotel e ci mettiamo in fila all&#8217;aeroporto Don Muang, enorme e pieno di gente soprattutto thai e cinesi. Colazione da Starbucks anche oggi, in volo non ci danno nulla e possiamo solo vedere un mare di nuvole sotto di noi, con la cappa di umidit\u00e0 che avvolge cielo e terra. Chiang Rai ci fa sentire tutta l&#8217;Asia che ci aspetta (e non abbiamo visto in dodici ore nella capitale), ci raggiunge la corrispondente locale ANM e caricati i bagagli su due pulmini&#8230; partiamo. Emozione a mille.<\/p>\n\n\n\n<p>L&#8217;aria di gruppo \u00e8 serena, con tanta voglia di conoscerci e scherzare in un crescendo che ci accompagner\u00e0 per tutto il viaggio anche nelle lunghe ore trascorse sul pulmino, con piccole discussioni costruttive ma senza mai brontolare o far pesare alcunch\u00e9.<\/p>\n\n\n\n<p>Chiang Khong \u00e8 la citt\u00e0 di confine con il Laos, distante 100 km da Chiang Rai. Guardate che bella dogana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-1024x768.jpg\" alt=\"\" class=\"wp-image-16611\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_110358.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Arriviamo alle 10,30 e ci mettiamo un&#8217;ora e mezza per sbrigare le formalit\u00e0, passaporti, foto, visto, e uscire infine dall&#8217;altra parte del fiume Mekong, un&#8217;altra presenza costante nel viaggio L-C. Welcome to Laos!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"829\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_114924-829x1024.jpg\" alt=\"\" class=\"wp-image-16610\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_114924-829x1024.jpg 829w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_114924-243x300.jpg 243w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_114924-768x948.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_114924.jpg 972w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/><\/figure>\n\n\n\n<p>Conosciamo Paeng, la nostra guida per i prossimi tre giorni che ci annuncia un viaggio&#8230; di sette ore per giungere a Muang Sing, attraversando i villaggi che visiteremo nei prossimi giorni. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-1024x768.jpg\" alt=\"\" class=\"wp-image-16609\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123525.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>In uno di questi effettuiamo una breve pausa pranzo in un ristorantino sgarrupato lungo la strada. Appena scesi dal pulmino vogliamo sgranchirci le gambe e siamo investiti dall&#8217;umidit\u00e0 elevatissima, che tocca la pelle poi ci entra nel naso e nelle ossa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-1024x768.jpg\" alt=\"\" class=\"wp-image-16616\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123455.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Eleggiamo il cassiere, Daniele \u00e8 davvero splendido per preparazione e pazienza (sono una coord casinista per chi non lo sapesse). Mangeremo un po&#8217; sempre le stesse cose semplici, fresche e buone.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123600-768x1024.jpg\" alt=\"\" class=\"wp-image-16617\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123600-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123600-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123600-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123600.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Riso bollito o fritto con pollo e verdure saltate, patatine fritte, oppure zuppa di noodles che fa bene anche con questo caldo umido. Beviamo tanta acqua ma anche coca cola, birra, caff\u00e8 e t\u00e8.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_124053-768x1024.jpg\" alt=\"\" class=\"wp-image-16618\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_124053-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_124053-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_124053-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_124053-rotated.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>E infine aiutiamo la digestione con la frutta fresca sempre squisita, come ananas e manghi.<\/p>\n\n\n\n<p>Nell&#8217;attiguo minimarket ci sono bibite in bottiglia, snack, biscotti e cibi conservati da prendere, il junkfood \u00e8 utile nelle lunghe ore di trasferimento sul pulmino.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-1024x768.jpg\" alt=\"\" class=\"wp-image-16619\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_123546.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La bellezza della natura che ci circonda \u00e8 struggente, verde dappertutto e poche semplici opere dell&#8217;uomo.<\/p>\n\n\n\n<p>Capanne e villaggi sono sparsi nel nulla. La verdezza \u00e8 la prima tonalit\u00e0 cromatica esteriore, la pace \u00e8 la prima sensazione interiore che i laotiani ci trasmettono a piene mani, con sguardi e sorrisi indimenticabili.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153534-768x1024.jpg\" alt=\"\" class=\"wp-image-16620\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153534-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153534-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153534-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153534.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Sar\u00e0 perch\u00e9 sono buddhisti e animisti. Scrivo sul diario: \u201c<em>Hanno la pace dentro e il sorriso fuori\u201d<\/em>.<\/p>\n\n\n\n<p>Come non essere d&#8217;accordo? Sono calmi e pacati, vien voglia di abbracciarli tutti.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153605-768x1024.jpg\" alt=\"\" class=\"wp-image-16621\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153605-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153605-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153605-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153605.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Vivono in condizioni basiche in dignitosa povert\u00e0, ma non ci negano un sorriso.<\/p>\n\n\n\n<p>Nei villaggi ci vengono incontro con un misto di curiosit\u00e0 e circospezione, molti sono restii a farsi fotografare, non parliamo dei miei selfie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-1024x768.jpg\" alt=\"\" class=\"wp-image-16606\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/01.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La natura selvaggia con le sue rigogliose foreste si alterna con le coltivazioni: bananeti, risaie verdissime e alberi della gomma con la ferita sul tronco da cui si ricava il prezioso caucci\u00f9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-1024x768.jpg\" alt=\"\" class=\"wp-image-16608\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-1024x768.jpg 1024w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-300x225.jpg 300w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-768x576.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-1000x750.jpg 1000w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-570x428.jpg 570w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338-330x248.jpg 330w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_153338.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Seduti sul pulmino vediamo tutto al rallentatore fra i saliscendi, le curve e le cunette sull&#8217;asfalto, pieno di buche e poco curato. Affrontiamo con fatica soprattutto le salite, il vecchio mezzo mezzo sbuffa e ci fa saltellare. Soprattutto io saltello sul seggiolino anteriore, posto esattamente sopra il motore, cos\u00ec mi scaldo il sedere e quando Franco prova a sedersi davanti al posto mio, glie lo cedo volentieri. Ma presto me lo rid\u00e0 e preferisce sedersi nuovamente sopra&#8230; l&#8217;ammortizzatore, con sobbalzi garantiti!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_120639-768x1024.jpg\" alt=\"\" class=\"wp-image-16607\" srcset=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_120639-768x1024.jpg 768w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_120639-225x300.jpg 225w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_120639-600x800.jpg 600w, https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_120639.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Ammiriamo un bel tramonto sulla foresta e arriviamo a Muang Sing per le ore 20, prendiamo posto in una guesthouse, anzi un Eco resort con bungalow sistemati intorno a un rigoglioso giardino fiorito. L&#8217;arredamento \u00e8 semplice, quasi da montagna, ceniamo sotto le fresche frasche.<\/p>\n\n\n\n<p>Qui alloggia uno dei tre gruppi ANM, questo fa il Tutto Laos. Dopo cena passeggiamo al chiaro della luna piena, i gruppi in Thailandia si godono uno spettacolo tanto cercato e desiderato (ma che non fa per me), il Full Moon Party! Siamo stanchi ma contenti, andiamo a dormire prima di mezzanotte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LUOGHI VISITATI<\/h2>\n\n\n\n<p>Legenda e anticipazioni<\/p>\n\n\n\n<p>UN significa che il sito \u00e8 inserito tra i patrimoni dell&#8217;umanit\u00e0 UNESCO. I villaggi quasi senza nome dove passiamo sono spesso una fila di capanne in legno, dove scorre la vita degli abitanti e degli animali che convivono fianco a fianco, ne costituiscono la semplice dieta e, nel caso dei bufali, anche un valido supporto nei lavori agricoli. I mercati delle diverse etnie sono quasi sempre una fila di capanne dove la gente espone i prodotti dei campi, animali vivi, funghi ecc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BANGKOK<\/h2>\n\n\n\n<p>Peccato per alcuni non avere tempo di una breve visita o pausa shopping, ma col nostro piano voli non ce la facevamo assolutamente. Ad maiora! Idem CHIANG RAI nel nord della Thailandia dove arriviamo col primo volo del mattino, il terzo giorno di viaggio (!!).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MUANG SING (spoiler)<\/h2>\n\n\n\n<p>La prima localit\u00e0 dove ci fermiamo per la notte \u00e8 una lunga striscia d&#8217;asfalto rattoppato circondato da case e negozi, con una zona decentrata arricchita da un bel tempio e soprattutto da un mercato stupendo. Prima delle sette di mattina \u00e8 gi\u00e0 affollato da venditori di ogni genere di prodotti alimentari, ma anche tessuti e oggetti per la casa, di acquirenti e&#8230; non di turisti. Siamo solo noi! Da pochi km fuori dal paese parte un interessantissima passeggiata di quasi sette ore nei villaggi delle diverse etnie, cultori di tradizioni ancestrali basate sull&#8217;animismo e la ricerca di un buon rapporto con la natura e i suoi spiriti. Si passeggia tra bananeti, alberi della gomma, piantagioni di canna da zucchero, in piano, senza pericolo di incorrere in visite sgradite come sanguisughe o altro. A met\u00e0 percorso, in un villaggio ci preparano un ottimo pranzo a base di riso, verdura, carne cotta e stufata. Esperienza toccante e molto aggregante per il gruppo.<\/p>\n\n\n\n<p>NdR \u2013 nota della Roberta. Questo \u00e8 un diario di viaggio come una volta, no consigli, poche info pratiche, ma tante impressioni ed emozioni tratte dal mio viaggio. Per le info ci sono le guide, il mio blog nasce per condividere e invogliare al viaggio. Le foto infine sono come me, senza fronzoli, se c&#8217;\u00e8 foschia sono fosche, se c&#8217;\u00e8 il sole sono luminose. Non c&#8217;\u00e8 trucco non c&#8217;\u00e8 inganno. Buona continuazione!<\/p>\n\n\n\n<p><em>Ti \u00e8 piaciuto questo post sul Laos e Cambogia? Se vuoi leggere anche gli altri cerca LAOS o CAMBOGIA con la lente nel menu a destra. E se vuoi commentare mi far\u00e0 piacere. Grazie! <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 \u2013 10 AGOSTO 2014 (aereo e bus) Scrivo sul diario: \u201cBella partenza con un gruppo bellissimo. Scrivo dal pulmino grande e senza A\/C nel tragitto da Huang Xai a Luang Namtha e Muang Sing, sono 200 km e l&#8217;autista dice che ci metteremo sei ore. Il nostro viaggio in L-C \u00e8 iniziato due giorni &hellip; <a class=\"more-link\" href=\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\">Leggi tutto<i class=\"ion-ios-arrow-thin-right\"><\/i><\/a><\/p>\n","protected":false},"author":2,"featured_media":16614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,33,707],"tags":[2927,2924],"class_list":["post-16604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-friends","category-travelling","category-viaggi-asia","tag-cambogia-avventure-nel-mondo","tag-laos-cambogia-avventure-nel-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AVVENTURE IN LAOS E CAMBOGIA: DALL&#039;ITALIA A BANGKOK E MUANG SING - Gamberetta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVENTURE IN LAOS E CAMBOGIA: DALL&#039;ITALIA A BANGKOK E MUANG SING - Gamberetta\" \/>\n<meta property=\"og:description\" content=\"8 \u2013 10 AGOSTO 2014 (aereo e bus) Scrivo sul diario: \u201cBella partenza con un gruppo bellissimo. Scrivo dal pulmino grande e senza A\/C nel tragitto da Huang Xai a Luang Namtha e Muang Sing, sono 200 km e l&#8217;autista dice che ci metteremo sei ore. Il nostro viaggio in L-C \u00e8 iniziato due giorni &hellip; Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\" \/>\n<meta property=\"og:site_name\" content=\"Gamberetta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Gamberettatravelblog\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-14T07:36:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-29T12:50:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gamberetta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@robertazennaro\" \/>\n<meta name=\"twitter:site\" content=\"@robertazennaro\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gamberetta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\",\"url\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\",\"name\":\"AVVENTURE IN LAOS E CAMBOGIA: DALL'ITALIA A BANGKOK E MUANG SING - Gamberetta\",\"isPartOf\":{\"@id\":\"https:\/\/www.gamberetta.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg\",\"datePublished\":\"2020-04-14T07:36:33+00:00\",\"dateModified\":\"2022-10-29T12:50:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/7a4a919927c944edb5f3f9c665590124\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage\",\"url\":\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg\",\"contentUrl\":\"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gamberetta.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVENTURE IN LAOS E CAMBOGIA: DALL&#8217;ITALIA A BANGKOK E MUANG SING\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/#website\",\"url\":\"https:\/\/www.gamberetta.it\/it\/\",\"name\":\"Gamberetta\",\"description\":\"Il mio blog senza fronzoli: pensieri e parole, sempre e ovunque in viaggio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gamberetta.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/7a4a919927c944edb5f3f9c665590124\",\"name\":\"gamberetta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7ef5d82656b8958070b4f589b7ae1784?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7ef5d82656b8958070b4f589b7ae1784?s=96&d=mm&r=g\",\"caption\":\"gamberetta\"},\"description\":\"Sono Toro ascendente Scorpione, terra di contrasti dove ora prevale una met\u00e0, ora l\u2019altra. L\u2019infanzia in Veneto e gli ultimi anni passati a Milano hanno sviluppato in me una serie ulteriore di conflitti. Scrivo da sempre, la scrittura \u00e8 la migliore forma espressiva che mi consente di fissare concetti altrimenti sospesi nell\u2019aria. Da bambina scrivevo poesie con uno stile quasi leopardiano poi sono passata ai diari di viaggio dalla prima volta in USA nel 1998 e non ho pi\u00f9 smesso...\",\"url\":\"https:\/\/www.gamberetta.it\/it\/author\/gamberettarossa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVENTURE IN LAOS E CAMBOGIA: DALL'ITALIA A BANGKOK E MUANG SING - Gamberetta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/","og_locale":"it_IT","og_type":"article","og_title":"AVVENTURE IN LAOS E CAMBOGIA: DALL'ITALIA A BANGKOK E MUANG SING - Gamberetta","og_description":"8 \u2013 10 AGOSTO 2014 (aereo e bus) Scrivo sul diario: \u201cBella partenza con un gruppo bellissimo. Scrivo dal pulmino grande e senza A\/C nel tragitto da Huang Xai a Luang Namtha e Muang Sing, sono 200 km e l&#8217;autista dice che ci metteremo sei ore. Il nostro viaggio in L-C \u00e8 iniziato due giorni &hellip; Leggi tutto","og_url":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/","og_site_name":"Gamberetta","article_publisher":"https:\/\/www.facebook.com\/Gamberettatravelblog","article_published_time":"2020-04-14T07:36:33+00:00","article_modified_time":"2022-10-29T12:50:25+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg","type":"image\/jpeg"}],"author":"gamberetta","twitter_card":"summary_large_image","twitter_creator":"@robertazennaro","twitter_site":"@robertazennaro","twitter_misc":{"Scritto da":"gamberetta","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/","url":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/","name":"AVVENTURE IN LAOS E CAMBOGIA: DALL'ITALIA A BANGKOK E MUANG SING - Gamberetta","isPartOf":{"@id":"https:\/\/www.gamberetta.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage"},"image":{"@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg","datePublished":"2020-04-14T07:36:33+00:00","dateModified":"2022-10-29T12:50:25+00:00","author":{"@id":"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/7a4a919927c944edb5f3f9c665590124"},"breadcrumb":{"@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#primaryimage","url":"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg","contentUrl":"https:\/\/www.gamberetta.it\/wp-content\/uploads\/2020\/04\/20140810_152823.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.gamberetta.it\/it\/2020\/04\/14\/avventure-in-laos-e-cambogia-dallitalia-a-bangkok-e-muang-sing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gamberetta.it\/it\/"},{"@type":"ListItem","position":2,"name":"AVVENTURE IN LAOS E CAMBOGIA: DALL&#8217;ITALIA A BANGKOK E MUANG SING"}]},{"@type":"WebSite","@id":"https:\/\/www.gamberetta.it\/it\/#website","url":"https:\/\/www.gamberetta.it\/it\/","name":"Gamberetta","description":"Il mio blog senza fronzoli: pensieri e parole, sempre e ovunque in viaggio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gamberetta.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/7a4a919927c944edb5f3f9c665590124","name":"gamberetta","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gamberetta.it\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7ef5d82656b8958070b4f589b7ae1784?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ef5d82656b8958070b4f589b7ae1784?s=96&d=mm&r=g","caption":"gamberetta"},"description":"Sono Toro ascendente Scorpione, terra di contrasti dove ora prevale una met\u00e0, ora l\u2019altra. L\u2019infanzia in Veneto e gli ultimi anni passati a Milano hanno sviluppato in me una serie ulteriore di conflitti. Scrivo da sempre, la scrittura \u00e8 la migliore forma espressiva che mi consente di fissare concetti altrimenti sospesi nell\u2019aria. Da bambina scrivevo poesie con uno stile quasi leopardiano poi sono passata ai diari di viaggio dalla prima volta in USA nel 1998 e non ho pi\u00f9 smesso...","url":"https:\/\/www.gamberetta.it\/it\/author\/gamberettarossa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/posts\/16604"}],"collection":[{"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/comments?post=16604"}],"version-history":[{"count":3,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/posts\/16604\/revisions"}],"predecessor-version":[{"id":19939,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/posts\/16604\/revisions\/19939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/media\/16614"}],"wp:attachment":[{"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/media?parent=16604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/categories?post=16604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gamberetta.it\/it\/wp-json\/wp\/v2\/tags?post=16604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}